{"id":23033,"date":"2022-08-21T13:29:58","date_gmt":"2022-08-21T13:29:58","guid":{"rendered":"https:\/\/karmeto.ir\/blog-test\/?p=23033"},"modified":"2024-09-20T14:05:11","modified_gmt":"2024-09-20T10:35:11","slug":"%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85","status":"publish","type":"post","link":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/","title":{"rendered":"\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0641\u0647\u0631\u0633\u062a \u0645\u0637\u0627\u0644\u0628<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#%D9%85%D8%A7%D8%AF%D9%87_244_%D9%82%D8%A7%D9%86%D9%88%D9%86_%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA_%D9%87%D8%A7%DB%8C_%D9%85%D8%B3%D8%AA%D9%82%DB%8C%D9%85\" >\u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#%D8%AF%D8%B3%D8%AA%D9%88%D8%B1%D8%A7%D9%84%D8%B9%D9%85%D9%84_%D9%88_%D8%A8%D8%AE%D8%B4%D9%86%D8%A7%D9%85%D9%87\" >\u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u0648 \u0628\u062e\u0634\u0646\u0627\u0645\u0647<\/a><\/li><\/ul><\/nav><\/div>\n<p dir=\"RTL\" style=\"text-align: justify; margin-bottom: 11px;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\"><span style=\"line-height: 107%;\"><span lang=\"FA\"><span style=\"line-height: 107%;\">\u0647\u0646\u06af\u0627\u0645 \u0628\u0631\u0648\u0632 \u0647\u0631\u06af\u0648\u0646\u0647 \u0627\u062e\u062a\u0644\u0627\u0641\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc\u060c \u062f\u0631\u0635\u0648\u0631\u062a\u06cc\u200c\u06a9\u0647 \u0645\u0631\u062c\u0639<\/span><\/span> <span lang=\"FA\"><span style=\"line-height: 107%;\">\u0642\u0627\u0646\u0648\u0646\u06cc \u00a0\u0627\u062e\u062a\u0644\u0627\u0641 \u0633\u0627\u0632\u0645\u0627\u0646 \u062f\u06cc\u06af\u0631\u06cc \u0646\u0628\u0627\u0634\u062f\u060c \u0645\u0633\u0626\u0648\u0644 \u0627\u0635\u0644\u06cc \u0631\u0633\u06cc\u062f\u06af\u06cc \u0628\u0647 \u0634\u06a9\u0627\u06cc\u0627\u062a \u0648 \u0628\u0631\u0631\u0633\u06cc \u0642\u0627\u0646\u0648\u0646\u06cc \u0627\u062e\u062a\u0644\u0627\u0641\u0627\u062a\u060c \u0647\u06cc\u0623\u062a \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641\u0627\u062a \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a. \u0637\u0628\u0642 \u0642\u0648\u0627\u0646\u06cc\u0646 \u0627\u06cc\u0646 \u0647\u06cc\u0623\u062a\u060c \u062f\u0631 \u0632\u0645\u0627\u0646 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06cc\u06a9 \u06af\u0631\u0648\u0647 \u06cc\u0627 \u0633\u0627\u0632\u0645\u0627\u0646\u060c \u0628\u0631\u0627\u06cc \u062d\u0644 \u0645\u0634\u06a9\u0644 \u0648 \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc \u0646\u0647\u0627\u06cc\u06cc\u060c \u0646\u06cc\u0627\u0632 \u0628\u0647 \u0631\u0627\u06cc\u200c\u06af\u06cc\u0631\u06cc \u0628\u0627 \u0633\u0647 \u0646\u0641\u0631 \u0627\u0632 \u0627\u0639\u0636\u0627 \u0642\u0627\u0646\u0648\u0646\u06cc \u0627\u0633\u062a.<\/span><\/span><\/span><\/span><\/span><\/p>\n<ol>\n<li style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\"><span style=\"line-height: 107%;\"><span lang=\"FA\"><span style=\"line-height: 107%;\">\u0646\u0641\u0631 \u0627\u0648\u0644\u060c \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0627\u0635\u0644\u06cc \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0627\u0633\u062a.<\/span><\/span><\/span><\/span><\/span><\/li>\n<li style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\"><span style=\"line-height: 107%;\"><span lang=\"FA\"><span style=\"line-height: 107%;\">\u0646\u0641\u0631 \u062f\u0648\u0645\u060c \u06cc\u06a9 \u0642\u0627\u0636\u06cc \u0634\u0627\u063a\u0644 \u06cc\u0627 \u0628\u0627\u0632\u0646\u0634\u0633\u062a\u0647 \u0627\u0633\u062a. \u0628\u0631\u0627\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0641\u0631\u062f \u0642\u0627\u0636\u06cc\u060c \u062f\u0631\u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0642\u0627\u0636\u06cc \u0628\u0627\u0632\u0646\u0634\u0633\u062a\u0647 \u0645\u0646\u0627\u0633\u0628 \u0648 \u0648\u0627\u062c\u062f \u0634\u0631\u0627\u06cc\u0637 \u062f\u0631 \u0627\u0633\u062a\u0627\u0646 \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0637\u0628\u0642 \u062e\u0648\u0627\u0633\u062a\u0647 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631\u060c \u0631\u0626\u06cc\u0633 \u0642\u0648\u0647 \u0642\u0636\u0627\u0626\u06cc\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u0642\u0627\u0636\u06cc \u0634\u0627\u063a\u0644 \u062e\u0628\u0631\u0647 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0647\u06cc\u0623\u062a \u0631\u0627\u06cc\u200c\u06af\u06cc\u0631\u06cc \u0645\u0639\u0631\u0641\u06cc \u06a9\u0646\u062f.<\/span><\/span><\/span><\/span><\/span><\/li>\n<li style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\"><span style=\"line-height: 107%;\"><span lang=\"FA\"><span style=\"line-height: 107%;\">\u0646\u0641\u0631 \u0633\u0648\u0645\u060c \u0634\u062e\u0635\u06cc \u0627\u0632 \u067e\u0646\u062c \u0627\u0631\u06af\u0627\u0646 \u0645\u062e\u062a\u0644\u0641 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0634\u062e\u0635 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0639\u0636\u0648\u06cc \u0627\u0632 \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc \u0648 \u0635\u0646\u0627\u06cc\u0639 \u0648 \u0645\u0639\u0627\u062f\u0646 \u062c\u0645\u0647\u0648\u0631\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0627\u062a\u0627\u0642 \u062a\u0639\u0627\u0648\u0646\u060c \u062c\u0627\u0645\u0639\u0647 \u062d\u0633\u0627\u0628\u062f\u0627\u0631\u0627\u0646 \u0631\u0633\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0645\u062c\u0627\u0645\u0639 \u062d\u0631\u0641\u0647\u200c\u0627\u06cc\u060c \u062a\u0634\u06a9\u0644\u200c\u0647\u0627\u06cc \u200c\u0635\u0646\u0641\u06cc \u0648 \u06cc\u0627 \u0634\u0648\u0631\u0627\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0634\u0647\u0631 \u0628\u0627\u0634\u062f \u0648 \u062f\u0631 \u0631\u0627\u06cc\u200c\u06af\u06cc\u0631\u06cc \u0647\u06cc\u0623\u062a \u0634\u0631\u06a9\u062a \u06a9\u0646\u062f.<\/span><\/span> <span lang=\"FA\"><span style=\"line-height: 107%;\">\u00a0\u062f\u0631\u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u200c \u0627\u0628\u0644\u0627\u063a \u0642\u0627\u0646\u0648\u0646\u06cc \u0628\u0631\u06af \u200c\u062a\u0634\u062e\u06cc\u0635 \u0645\u0627\u0644\u06cc\u0627\u062a \u0631\u062e \u062f\u0647\u062f \u0648 \u0634\u062e\u0635 \u06cc\u0627 \u06af\u0631\u0648\u0647 \u0645\u0639\u062a\u0631\u0636\u060c \u0647\u0645\u0632\u0645\u0627\u0646 \u0628\u0627 \u062a\u0633\u0644\u06cc\u0645 \u0627\u0639\u062a\u0631\u0627\u0636 \u0628\u0647 \u0628\u0631\u06af \u062a\u0634\u062e\u06cc\u0635\u060c \u062f\u0631 \u0645\u062f\u062a \u0632\u0645\u0627\u0646 \u0645\u0639\u06cc\u0646 \u0642\u0627\u0646\u0648\u0646\u06cc\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u062e\u0648\u062f \u0631\u0627 \u0627\u0639\u0644\u0627\u0645 \u0646\u06a9\u0646\u062f\u060c \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0628\u0627 \u0628\u0631\u0631\u0633\u06cc \u0648 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u0648\u0636\u0648\u0639 \u0634\u06a9\u0627\u06cc\u062a \u0648 \u0627\u062e\u062a\u0644\u0627\u0641\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0634\u062e\u0627\u0635 \u0630\u06a9\u0631\u0634\u062f\u0647 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0631\u0627\u06cc\u200c\u06af\u06cc\u0631\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc\u200c\u06a9\u0646\u062f. <\/span><\/span><\/span><\/span><\/span><\/li>\n<\/ol>\n<p dir=\"RTL\" style=\"text-align: justify; margin-bottom: 11px;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\"><span style=\"line-height: 107%;\"><span lang=\"FA\"><span style=\"line-height: 107%;\">\u0628\u0627\u06cc\u062f \u0627\u0634\u0627\u0631\u0647 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0637\u0628\u0642 \u062a\u0628\u0635\u0631\u0647 \u0627\u0648\u0644 \u0648 \u062f\u0648\u0645 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647\u060c \u062c\u0644\u0633\u0627\u062a \u0647\u06cc\u0623\u062a\u200c\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u0627 \u062d\u0636\u0648\u0631 \u0627\u06cc\u0646 \u0633\u0647 \u0646\u0641\u0631 \u0631\u0633\u0645\u06cc \u0627\u0633\u062a \u0648 \u062a\u0635\u0645\u06cc\u0645 \u0646\u0647\u0627\u06cc\u06cc \u0637\u0628\u0642 \u0646\u0638\u0631 \u0627\u06a9\u062b\u0631\u06cc\u062a \u0622\u0631\u0627 \u062a\u0639\u06cc\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0628\u0627 \u0627\u06cc\u0646\u200c\u062d\u0627\u0644 \u0646\u0638\u0631 \u0627\u0641\u0631\u0627\u062f \u0627\u0642\u0644\u06cc\u062a \u0647\u0645 \u0628\u0627\u06cc\u062f \u062f\u0631 \u06af\u0632\u0627\u0631\u0634 \u0642\u0627\u0646\u0648\u0646\u06cc \u0630\u06a9\u0631 \u0634\u0648\u062f. \u0627\u062f\u0627\u0631\u0647 \u0648 \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u062a\u0634\u06a9\u06cc\u0644 \u0627\u06cc\u0646 \u062c\u0644\u0633\u0627\u062a \u0628\u0631 \u0639\u0647\u062f\u0647 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0627\u0633\u062a \u0648 \u062d\u0642\u200c\u0627\u0644\u0632\u062d\u0645\u0647 \u0627\u0641\u0631\u0627\u062f \u0634\u0631\u06a9\u062a\u200c\u06a9\u0646\u0646\u062f\u0647 \u062f\u0631 \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc\u060c \u0628\u0647 \u062a\u0635\u0648\u06cc\u0628 \u0648\u0632\u06cc\u0631 \u0627\u0645\u0648\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc\u060c \u0627\u0632 \u0628\u0648\u062f\u062c\u0647 \u0633\u0627\u0632\u0645\u0627\u0646 \u0645\u0630\u06a9\u0648\u0631 \u067e\u0631\u062f\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/span><\/span><\/span><\/span><\/p>\n<p dir=\"RTL\" style=\"margin-bottom: 11px; text-align: center;\"><strong>\u0628\u0631\u0627\u06cc \u06a9\u0633\u0628 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u0628\u0627 \u0645\u0634\u0627\u0648\u0631\u0627\u0646 \u0628\u062e\u0634\u00a0<a href=\"https:\/\/karmento.ir\/service\/1\/%D9%85%D8%B4%D8%A7%D9%88%D8%B1%D9%87-%D9%85%D8%A7%D9%84%DB%8C-%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA%DB%8C\"><span style=\"color: #2980b9;\">\u0645\u0634\u0627\u0648\u0631\u0647 \u0645\u0627\u0644\u06cc<\/span><\/a> \u00a0\u06a9\u0627\u0631\u0645\u0646\u062a\u0648 \u0647\u0645\u0631\u0627\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/strong><\/p>\n<h2 dir=\"RTL\" style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%A7%D8%AF%D9%87_244_%D9%82%D8%A7%D9%86%D9%88%D9%86_%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA_%D9%87%D8%A7%DB%8C_%D9%85%D8%B3%D8%AA%D9%82%DB%8C%D9%85\"><\/span><span style=\"background: white;\"><span style=\"line-height: 24.0pt;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\">\u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/span><\/span><\/span><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"RTL\" style=\"text-align: justify;\"><span style=\"background: white;\"><span style=\"line-height: 24.0pt;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\"><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">)<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\"> \u0627\u0635\u0644\u0627\u062d\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f3\u06f9\u06f9\/\u06f0\u06f9\/\u06f0\u06f5)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0645\u0631\u062c\u0639 \u0631\u0633\u06cc\u062f\u06af\u06cc \u0628\u0647 \u06a9\u0644\u06cc\u0647 \u0627\u062e\u062a\u0644\u0627\u0641 \u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062c\u0632 \u062f\u0631 \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u0636\u0645\u0646 \u0645\u0642\u0631\u0631\u0627\u062a \u0627\u06cc\u0646 \u0642\u0627\u0646\u0648\u0646 \u0645\u0631\u062c\u0639 \u062f\u06cc\u06af\u0631\u06cc \u067e\u06cc\u0634 \u200c\u0628\u06cc\u0646\u06cc \u200c\u0634\u062f\u0647\u200c\u060c \u0647\u06cc\u0623\u062a \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641\u0627\u062a \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a\u200c. \u0647\u0631 \u0647\u06cc\u0623\u062a \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u200c\u0627\u0632 \u0633\u0647 \u0646\u0641\u0631 \u0628\u0647 \u200c\u0634\u0631\u062d \u0632\u06cc\u0631 \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc \u200c\u0634\u0648\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">:<\/span><\/span><\/span><br \/>\n<span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u200c<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\"> &#8211; <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06cc\u06a9 \u0646\u0641\u0631 \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631<\/span><\/span><\/span><br \/>\n<span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2\u200c<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\"> &#8211; <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06cc\u06a9 \u0646\u0641\u0631 \u0627\u0632 \u0645\u06cc\u0627\u0646 \u0642\u0636\u0627\u062a \u0628\u0627\u0632\u0646\u0634\u0633\u062a\u0647 \u06cc\u0627 \u062d\u0642\u0648\u0642 \u062f\u0627\u0646\u0627\u0646 \u0645\u0637\u0644\u0639 \u062f\u0631 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u0627 \u0634\u0631\u0637 \u0648\u062b\u0627\u0642\u062a \u0648 \u0627\u0645\u0627\u0646\u062a \u0628\u0647 \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0648 \u0627\u0646\u062a\u062e\u0627\u0628 \u0631\u0626\u06cc\u0633 \u06a9\u0644 \u062f\u0627\u062f\u06af\u0633\u062a\u0631\u06cc \u0647\u0631 \u0627\u0633\u062a\u0627\u0646<\/span><\/span><\/span><br \/>\n<span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3\u200c<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\"> &#8211; <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06cc\u06a9 \u0646\u0641\u0631 \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0627\u0632 \u0627\u062a\u0627\u0642 \u0628\u0627\u0632\u0631\u06af\u0627\u0646\u06cc\u060c \u0635\u0646\u0627\u06cc\u0639 \u0648 \u0645\u0639\u0627\u062f\u0646 \u0648 \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0627\u062a\u0627\u0642 \u062a\u0639\u0627\u0648\u0646 \u0627\u06cc\u0631\u0627\u0646\u060c \u062c\u0627\u0645\u0639\u0647 \u062d\u0633\u0627\u0628\u062f\u0627\u0631\u0627\u0646 \u0631\u0633\u0645\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u062c\u0627\u0645\u0639\u0647 \u0645\u0634\u0627\u0648\u0631\u0627\u0646 \u0631\u0633\u0645\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0645\u062c\u0627\u0645\u0639 \u062d\u0631\u0641\u0647 \u200c\u0627\u06cc\u060c \u0627\u062a\u0627\u0642 \u0627\u0635\u0646\u0627\u0641 \u0627\u06cc\u0631\u0627\u0646\u060c \u0634\u0648\u0631\u0627\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc \u0634\u0647\u0631\u060c \u06a9\u0627\u0646\u0648\u0646 \u0648\u06a9\u0644\u0627\u060c \u0645\u0631\u06a9\u0632 \u0648\u06a9\u0644\u0627\u060c\u200c \u06a9\u0627\u0631\u0634\u0646\u0627\u0633\u0627\u0646 \u0631\u0633\u0645\u06cc \u0648 \u0645\u0634\u0627\u0648\u0631\u0627\u0646 \u062e\u0627\u0646\u0648\u0627\u062f\u0647 \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0645\u062f\u062a \u0633\u0647 \u200c\u0633\u0627\u0644 \u0645\u0646\u0635\u0648\u0628 \u0645\u06cc\u200c \u0634\u0648\u0646\u062f. \u0645\u0648\u062f\u06cc \u0647\u0645\u0632\u0645\u0627\u0646 \u0628\u0627 \u0627\u0639\u062a\u0631\u0627\u0636 \u0628\u0647 \u0628\u0631\u06af \u062a\u0634\u062e\u06cc\u0635 \u06cc\u0627 \u0645\u0637\u0627\u0644\u0628\u0647 \u0645\u0627\u0644\u06cc\u0627\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0631\u0627\u062c\u0639 \u0627\u06cc\u0646 \u0628\u0646\u062f \u0631\u0627 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u062e\u0648\u062f \u062c\u0647\u062a \u0634\u0631\u06a9\u062a \u062f\u0631 \u062c\u0644\u0633\u0627\u062a \u0647\u06cc\u0623\u062a \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u0639\u0631\u0641\u06cc \u0645\u06cc \u200c\u0646\u0645\u0627\u06cc\u062f. \u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u0631\u06af \u200c\u062a\u0634\u062e\u06cc\u0635 \u0645\u0627\u0644\u06cc\u0627\u062a \u0627\u0628\u0644\u0627\u063a \u0642\u0627\u0646\u0648\u0646\u06cc \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u0648 \u06cc\u0627 \u0647\u0645\u0632\u0645\u0627\u0646 \u0628\u0627 \u062a\u0633\u0644\u06cc\u0645 \u200c\u0627\u0639\u062a\u0631\u0627\u0636 \u0628\u0647 \u0628\u0631\u06af \u062a\u0634\u062e\u06cc\u0635 \u062f\u0631 \u0645\u0647\u0644\u062a \u0642\u0627\u0646\u0648\u0646\u06cc \u0645\u0648\u062f\u06cc \u0627\u0646\u062a\u062e\u0627\u0628 \u062e\u0648\u062f \u0631\u0627 \u0627\u0639\u0644\u0627\u0645 \u0646\u0646\u0645\u0627\u06cc\u062f\u060c \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0646\u0648\u0639 \u0641\u0639\u0627\u0644\u06cc\u062a \u0645\u0648\u062f\u06cc \u06cc\u0627 \u0645\u0648\u0636\u0648\u0639 \u0645\u0627\u0644\u06cc\u0627\u062a \u0645\u0648\u0631\u062f \u0631\u0633\u06cc\u062f\u06af\u06cc\u060c \u0627\u0632 \u0628\u06cc\u0646 \u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u0627\u0646 \u0645\u0632\u0628\u0648\u0631 \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u062a\u0628\u0635\u0631\u0647 (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f5) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u200c\u06cc\u06a9 \u0646\u0641\u0631 \u0627\u0646\u062a\u062e\u0627\u0628 \u0645\u06cc \u200c\u0634\u0648\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1 (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0635\u0644\u0627\u062d\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f3\u06f8\u06f0\/\u06f1\u06f1\/\u06f2\u06f7)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062c\u0644\u0633\u0627\u062a \u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u0627 \u062d\u0636\u0648\u0631 \u0647\u0631 \u0633\u0647 \u0639\u0636\u0648 \u0631\u0633\u0645\u06cc\u062a \u0645\u06cc \u200c\u06cc\u0627\u0628\u062f \u0648 \u0631\u0623\u06cc \u0647\u06cc\u0623\u062a \u0628\u0627 \u0627\u06a9\u062b\u0631\u06cc\u062a \u0622\u0631\u0627\u0621 \u0642\u0637\u0639\u06cc \u0648 \u0644\u0627\u0632\u0645 \u200c\u0627\u0644\u0627\u062c\u0631\u0627\u0621 \u0627\u0633\u062a\u060c \u0648\u0644\u06cc \u0646\u0638\u0631 \u0627\u0642\u0644\u06cc\u062a \u0628\u0627\u06cc\u062f \u062f\u0631 \u0645\u062a\u0646 \u0631\u0623\u06cc \u0642\u06cc\u062f \u06af\u0631\u062f\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2 (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0635\u0644\u0627\u062d\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f3\u06f8\u06f0\/\u06f1\u06f1\/\u06f2\u06f7)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062f\u0627\u0631\u0627\u06cc \u0627\u0633\u062a\u0642\u0644\u0627\u0644 \u06a9\u0627\u0645\u0644 \u0628\u0648\u062f\u0647 \u0648 \u0635\u0631\u0641\u0627\u064b \u0627\u062f\u0627\u0631\u0647 \u0627\u0645\u0648\u0631 \u062f\u0628\u06cc\u0631\u062e\u0627\u0646\u0647 \u200c\u0627\u06cc \u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0648 \u062a\u0634\u06a9\u06cc\u0644 \u062c\u0644\u0633\u0627\u062a \u0647\u06cc\u0623\u062a\u0647\u0627 \u0628\u0647 \u0639\u0647\u062f\u0647 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u06cc \u200c\u0628\u0627\u0634\u062f. \u0627\u0646\u0634\u0627\u06cc \u0631\u0623\u06cc \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u0627\u0635\u0644 \u0639\u062f\u0627\u0644\u062a \u0648 \u0628\u06cc\u200c \u0637\u0631\u0641\u06cc \u06a9\u0644\u06cc\u0647 \u0627\u0639\u0636\u0627 \u0648 \u0645\u062a\u06a9\u06cc \u0628\u0647 \u0627\u0633\u0646\u0627\u062f \u0648 \u0645\u062f\u0627\u0631\u06a9 \u0645\u062b\u0628\u062a\u0647 \u0648 \u062f\u0644\u0627\u06cc\u0644 \u0648 \u0634\u0648\u0627\u0647\u062f \u0645\u062a\u0642\u0646 \u062f\u0631 \u0647\u0645\u0627\u0646 \u062c\u0644\u0633\u0647 \u0648 \u06cc\u0627 \u062d\u062f\u0627\u06a9\u062b\u0631 \u0638\u0631\u0641 \u0633\u0647 \u0631\u0648\u0632 \u06a9\u0627\u0631\u06cc \u067e\u0633 \u0627\u0632 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u062c\u0644\u0633\u0647\u060c \u062a\u0648\u0633\u0637 \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0628\u0646\u062f (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647\u200c \u0628\u0647 \u0639\u0645\u0644 \u0622\u0645\u062f\u0647 \u0648 \u0628\u0647 \u0627\u0645\u0636\u0627\u06cc \u062a\u0645\u0627\u0645\u06cc \u0627\u0639\u0636\u0627 \u0645\u06cc \u200c\u0631\u0633\u062f. \u0645\u0648\u062f\u06cc \u06cc\u0627 \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0642\u0627\u0646\u0648\u0646\u06cc \u0648\u06cc \u0645\u062c\u0627\u0632 \u0628\u0647 \u062d\u0636\u0648\u0631 \u06a9\u0627\u0645\u0644 \u062f\u0631 \u062c\u0644\u0633\u0647 \u0648 \u0627\u0631\u0627\u0626\u0647 \u062f\u0641\u0627\u0639\u06cc\u0627\u062a \u0628\u0647 \u0635\u0648\u0631\u062a \u06a9\u062a\u0628\u06cc \u06cc\u0627 \u0634\u0641\u0627\u0647\u06cc \u0627\u0633\u062a. \u0627\u0638\u0647\u0627\u0631\u0627\u062a \u0634\u0641\u0627\u0647\u06cc \u0628\u0627\u06cc\u062f \u062f\u0631 \u0635\u0648\u0631\u062a\u062c\u0644\u0633\u0647 \u0642\u06cc\u062f \u0648 \u0628\u0647 \u0627\u0645\u0636\u0627\u06cc \u0648\u06cc \u0628\u0631\u0633\u062f. \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u0647 \u200c\u0645\u0646\u0638\u0648\u0631 \u0627\u0639\u0645\u0627\u0644 \u0646\u0638\u0627\u0631\u062a \u0645\u0648\u062b\u0631 \u0628\u0631 \u0639\u0645\u0644\u06a9\u0631\u062f \u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc\u060c \u0645\u06a9\u0644\u0641 \u0627\u0633\u062a \u0646\u0633\u0628\u062a \u0628\u0647 \u0645\u0633\u062a\u0646\u062f\u0633\u0627\u0632\u06cc \u0641\u0631\u0622\u06cc\u0646\u062f \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u062c\u0644\u0633\u0627\u062a \u0647\u06cc\u0623\u062a \u0628\u0647 \u0646\u062d\u0648 \u0645\u0642\u062a\u0636\u06cc \u0627\u0642\u062f\u0627\u0645 \u06a9\u0646\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3 (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0639\u06cc\u06cc\u0646 \u062d\u0642\u200c \u0627\u0644\u0632\u062d\u0645\u0647 \u0627\u0639\u0636\u0627\u06cc \u0645\u0648\u0636\u0648\u0639 \u0628\u0646\u062f\u0647\u0627\u06cc (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0648 (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u200c\u0645\u062a\u0646\u0627\u0633\u0628 \u0628\u0627 \u062a\u0639\u062f\u0627\u062f \u0648 \u0645\u062f\u062a \u062c\u0644\u0633\u0627\u062a \u0648 \u0646\u06cc\u0632 \u0645\u0631\u0627\u062d\u0644\u060c \u0645\u0646\u0627\u0628\u0639 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0648 \u067e\u0631\u0648\u0646\u062f\u0647\u200c \u0647\u0627\u06cc \u0645\u0648\u0631\u062f \u0631\u0633\u06cc\u062f\u06af\u06cc \u0627\u0632 \u0645\u062d\u0644 \u0627\u0639\u062a\u0628\u0627\u0631\u06cc \u200c\u06a9\u0647 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u0645\u0646\u0638\u0648\u0631 \u062f\u0631 \u0628\u0648\u062f\u062c\u0647 \u0633\u0627\u0644\u0627\u0646\u0647 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u067e\u06cc\u0634 \u200c\u0628\u06cc\u0646\u06cc \u0645\u06cc\u200c \u0634\u0648\u062f\u060c \u0645\u0637\u0627\u0628\u0642 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0633\u0627\u0632\u0645\u0627\u0646 \u0645\u0630\u06a9\u0648\u0631 \u062a\u0647\u06cc\u0647 \u0648 \u0627\u0628\u0644\u0627\u063a \u0645\u06cc \u200c\u06af\u0631\u062f\u062f. \u062d\u0642 \u200c\u0627\u0644\u0632\u062d\u0645\u0647 \u0627\u0639\u0636\u0627 \u0628\u0647\u200c \u0635\u0648\u0631\u062a \u0645\u062a\u0645\u0631\u06a9\u0632 \u0627\u0632 \u0637\u0631\u0641 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0628\u0647 \u062d\u0633\u0627\u0628 \u0627\u0639\u0636\u0627 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u06cc \u200c\u0634\u0648\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f4 (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u06a9\u0644\u0641 \u0627\u0633\u062a \u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u0627\u0646 \u0645\u0639\u0631\u0641\u06cc\u200c \u0634\u062f\u0647 \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0628\u0646\u062f\u0647\u0627\u06cc (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0648 (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647\u200c \u0631\u0627 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u0627\u0639\u0636\u0627\u06cc \u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u067e\u0630\u06cc\u0631\u062f \u0648 \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u062a\u0628\u0635\u0631\u0647 (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f5) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647\u200c \u0627\u0632 \u0622\u0646\u0647\u0627 \u062c\u0647\u062a \u0634\u0631\u06a9\u062a \u062f\u0631 \u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u0645\u0632\u0628\u0648\u0631 \u062f\u0639\u0648\u062a \u0646\u0645\u0627\u06cc\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f5 (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0633\u0627\u0645\u06cc \u06a9\u0644\u06cc\u0647 \u0627\u0641\u0631\u0627\u062f \u0645\u0639\u0631\u0641\u06cc\u200c \u0634\u062f\u0647 \u062a\u0648\u0633\u0637 \u0631\u0626\u06cc\u0633 \u06a9\u0644 \u062f\u0627\u062f\u06af\u0633\u062a\u0631\u06cc \u0647\u0631 \u0627\u0633\u062a\u0627\u0646\u060c \u0645\u062f\u06cc\u0631 \u06a9\u0644 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a\u0627\u0646 \u0648 \u0645\u0631\u0627\u062c\u0639 \u0645\u0630\u06a9\u0648\u0631 \u062f\u0631 \u0628\u0646\u062f (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u200c\u0628\u0647 \u062a\u0641\u06a9\u06cc\u06a9 \u0634\u0647\u0631\u0633\u062a\u0627\u0646 \u200c\u0647\u0627 \u062f\u0631 \u0633\u0627\u0645\u0627\u0646\u0647 \u200c\u0627\u06cc \u06a9\u0647 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u062a\u0645\u0631\u06a9\u0632 \u0648 \u062d\u062f\u0627\u06a9\u062b\u0631 \u0638\u0631\u0641 \u0633\u0647\u200c \u0645\u0627\u0647 \u067e\u0633 \u0627\u0632 \u0644\u0627\u0632\u0645 \u200c\u0627\u0644\u0627\u062c\u0631\u0627\u0621 \u0634\u062f\u0646 \u0627\u06cc\u0646 \u0642\u0627\u0646\u0648\u0646 \u062a\u0648\u0633\u0637 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c \u0634\u0648\u062f\u060c \u062f\u0631\u062c \u0645\u06cc \u200c\u06af\u0631\u062f\u062f. \u0627\u0646\u062a\u062e\u0627\u0628 \u0627\u0641\u0631\u0627\u062f \u0645\u0648\u0636\u0648\u0639 \u0628\u0646\u062f\u0647\u0627\u06cc (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1)<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u060c (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0648 (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0628\u0631\u0627\u06cc \u0647\u0631 \u067e\u0631\u0648\u0646\u062f\u0647 \u062f\u0631 \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0634\u0647\u0631\u0633\u062a\u0627\u0646 \u0645\u0648\u0631\u062f \u0646\u0638\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u06cc\u06a9 \u0646\u0641\u0631 \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0628\u0647 \u0635\u0648\u0631\u062a \u062a\u0635\u0627\u062f\u0641\u06cc \u062a\u0648\u0633\u0637 \u0633\u0627\u0645\u0627\u0646\u0647 \u0645\u0632\u0628\u0648\u0631 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc \u200c\u0634\u0648\u062f. \u0627\u06cc\u0646 \u0633\u0627\u0645\u0627\u0646\u0647 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627\u064b \u0632\u06cc\u0631 \u0646\u0638\u0631 \u0631\u0626\u06cc\u0633 \u06a9\u0644 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u06cc \u200c\u06af\u0631\u062f\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f6\u200c (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0645\u06a9\u0644\u0641 \u0627\u0633\u062a \u062d\u062f\u0627\u0642\u0644 \u06cc\u06a9 \u0647\u0641\u062a\u0647 \u0642\u0628\u0644 \u0627\u0632 \u062a\u0634\u06a9\u06cc\u0644 \u062c\u0644\u0633\u0647 \u0647\u06cc\u0623\u062a \u0628\u0647 \u0646\u062d\u0648 \u0645\u0642\u062a\u0636\u06cc \u0632\u0645\u06cc\u0646\u0647 \u062f\u0633\u062a\u0631\u0633\u06cc \u0627\u0639\u0636\u0627\u06cc \u0647\u06cc\u0623\u062a \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0631\u0627 \u0628\u0631\u0627\u0628\u0631 \u0645\u0642\u0631\u0631\u0627\u062a \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0645\u0646\u062f\u0631\u062c\u0627\u062a \u067e\u0631\u0648\u0646\u062f\u0647 \u0645\u0648\u0631\u062f \u0627\u0639\u062a\u0631\u0627\u0636 \u0641\u0631\u0627\u0647\u0645 \u0646\u0645\u0627\u06cc\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f7\u200c (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0647\u0631 \u06cc\u06a9 \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0645\u0630\u06a9\u0648\u0631 \u062f\u0631 \u0628\u0646\u062f\u0647\u0627\u06cc (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0648 (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u200c\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0633\u0647 \u062c\u0644\u0633\u0647 \u0645\u062a\u0648\u0627\u0644\u06cc \u06cc\u0627 \u0686\u0647\u0627\u0631 \u062c\u0644\u0633\u0647 \u0645\u062a\u0646\u0627\u0648\u0628 \u062f\u0631 \u06cc\u06a9 \u0633\u0627\u0644 \u0627\u0632 \u062d\u0636\u0648\u0631 \u062f\u0631 \u062c\u0644\u0633\u0627\u062a \u0647\u06cc\u0623\u062a \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u0646\u0645\u0627\u06cc\u0646\u062f\u060c \u062d\u06a9\u0645 \u0622\u0646\u0627\u0646 \u0644\u063a\u0648 \u0645\u06cc \u200c\u0634\u0648\u062f \u0648 \u0631\u0626\u06cc\u0633 \u06a9\u0644 \u062f\u0627\u062f\u06af\u0633\u062a\u0631\u06cc \u0647\u0631 \u0627\u0633\u062a\u0627\u0646 \u0648 \u0645\u0631\u062c\u0639 \u0645\u0631\u0628\u0648\u0637\u060c \u062d\u0633\u0628 \u0645\u0648\u0631\u062f\u060c \u0645\u0648\u0638\u0641 \u0627\u0633\u062a \u0638\u0631\u0641 \u062f\u0647 \u200c\u0631\u0648\u0632 \u06a9\u0627\u0631\u06cc \u0641\u0631\u062f \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u0646\u0645\u0627\u06cc\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f8\u200c (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0627\u062c\u0631\u0627\u06cc \u0639\u062f\u0627\u0644\u062a \u0648 \u0627\u0635\u0644 \u0627\u0633\u062a\u0642\u0644\u0627\u0644 \u0648 \u0628\u06cc\u200c \u0637\u0631\u0641\u06cc \u0648 \u0631\u0639\u0627\u06cc\u062a \u062d\u0642\u0648\u0642 \u0634\u0647\u0631\u0648\u0646\u062f\u06cc \u0648 \u0646\u0638\u0627\u0631\u062a \u0645\u0648\u062b\u0631\u060c \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u06a9\u0644\u0641 \u0627\u0633\u062a \u0633\u0627\u062e\u062a\u0627\u0631 \u0627\u062f\u0627\u0631\u0647 \u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0631\u0627 \u0628\u0647\u200c \u0635\u0648\u0631\u062a \u0645\u0633\u062a\u0642\u0644\u060c \u062a\u062d\u062a \u0639\u0646\u0648\u0627\u0646 \u0645\u0631\u06a9\u0632 \u062f\u0627\u062f\u0631\u0633\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062f\u0631 \u0633\u0627\u062e\u062a\u0627\u0631 \u062e\u0648\u062f \u0630\u06cc\u0644 \u0631\u0626\u06cc\u0633 \u06a9\u0644 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u06cc\u062c\u0627\u062f \u0646\u0645\u0627\u06cc\u062f. \u0648\u0627\u062d\u062f\u0647\u0627\u06cc \u062f\u0627\u062f\u0631\u0633\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062f\u0631 \u0647\u0631 \u0627\u0633\u062a\u0627\u0646 \u0645\u0633\u062a\u0642\u0644 \u0627\u0632 \u0627\u062f\u0627\u0631\u0647 \u06a9\u0644 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0633\u062a\u0627\u0646 \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc \u200c\u0634\u0648\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f9\u200c (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u067e\u0633 \u0627\u0632 \u0627\u0633\u062a\u0642\u0631\u0627\u0631 \u0633\u0627\u0645\u0627\u0646\u0647 \u0645\u0648\u062f\u06cc\u0627\u0646\u060c \u062b\u0628\u062a \u0627\u0639\u062a\u0631\u0627\u0636 \u062a\u0648\u0633\u0637 \u0645\u0648\u062f\u06cc\u060c \u0627\u0646\u062a\u062e\u0627\u0628 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0631\u0627\u062c\u0639 \u0645\u0648\u0636\u0648\u0639 \u0628\u0646\u062f (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u06cc\u0646 \u0645\u0627\u062f\u0647\u060c \u0627\u0631\u0627\u0626\u0647 \u0647\u0631\u06af\u0648\u0646\u0647 \u0644\u0627\u06cc\u062d\u0647 \u0628\u0647 \u0647\u06cc\u0623\u062a\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641\u060c \u0645\u0634\u0627\u0647\u062f\u0647 \u0627\u0633\u0646\u0627\u062f\u060c \u0645\u062f\u0627\u0631\u06a9 \u0648 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632\u060c \u0627\u0628\u0644\u0627\u063a \u062a\u0627\u0631\u06cc\u062e \u062a\u0634\u06a9\u06cc\u0644 \u062c\u0644\u0633\u0627\u062a \u0647\u06cc\u0623\u062a\u060c \u0627\u0637\u0644\u0627\u0639 \u0627\u0632 \u0646\u062a\u0627\u06cc\u062c \u062f\u0627\u062f\u0631\u0633\u06cc \u0648 \u0647\u0631\u06af\u0648\u0646\u0647 \u0627\u0637\u0644\u0627\u0639 \u062f\u06cc\u06af\u0631 \u062f\u0631 \u062e\u0635\u0648\u0635 \u067e\u0631\u0648\u0646\u062f\u0647 \u062f\u0627\u062f\u0631\u0633\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0633\u0627\u0645\u0627\u0646\u0647 \u0645\u0630\u06a9\u0648\u0631 \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc \u200c\u0634\u0648\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f0\u200c (<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0645\u06a9\u0644\u0641 \u0627\u0633\u062a \u0632\u0645\u06cc\u0646\u0647 \u062f\u0633\u062a\u0631\u0633\u06cc \u06a9\u0627\u0645\u0644 \u0645\u0648\u062f\u06cc \u0648 \u06cc\u0627 \u0646\u0645\u0627\u06cc\u0646\u062f\u0647 \u0642\u0627\u0646\u0648\u0646\u06cc \u0648\u06cc \u0628\u0647 \u0645\u0641\u0627\u062f \u067e\u0631\u0648\u0646\u062f\u0647 \u0645\u0648\u0631\u062f \u0627\u0639\u062a\u0631\u0627\u0636 \u0631\u0627 \u062d\u062f\u0627\u0642\u0644 \u06cc\u06a9 \u0647\u0641\u062a\u0647 \u0642\u0628\u0644 \u0627\u0632 \u062a\u0634\u06a9\u06cc\u0644 \u0647\u06cc\u0623\u062a \u0641\u0631\u0627\u0647\u0645 \u0646\u0645\u0627\u06cc\u062f<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><br \/>\n<span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u062a\u0628\u0635\u0631\u0647 <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f1 \u200c(<\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0644\u062d\u0627\u0642\u06cc <\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)- <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0639\u0636\u0648\u06cc\u062a \u0647\u0645\u0632\u0645\u0627\u0646 \u062f\u0631 \u0641\u0647\u0631\u0633\u062a \u0646\u0645\u0627\u06cc\u0646\u062f\u06af\u0627\u0646 \u0628\u0646\u062f\u0647\u0627\u06cc (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f2) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0648 (<\/span><\/span><\/span><span lang=\"FA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u06f3) <\/span><\/span><\/span><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0645\u0648\u0636\u0648\u0639 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u200c\u0645\u0645\u0646\u0648\u0639<\/span><\/span><\/span> <span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">\u0627\u0633\u062a<\/span><\/span><\/span><span dir=\"LTR\"><span style=\"background: white;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<h2 style=\"margin-bottom: 11px; text-align: justify;\"><span class=\"ez-toc-section\" id=\"%D8%AF%D8%B3%D8%AA%D9%88%D8%B1%D8%A7%D9%84%D8%B9%D9%85%D9%84_%D9%88_%D8%A8%D8%AE%D8%B4%D9%86%D8%A7%D9%85%D9%87\"><\/span><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u0648 \u0628\u062e\u0634\u0646\u0627\u0645\u0647<\/span><\/span><\/span><\/span><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><strong><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0627\u062c\u0631\u0627\u06cc \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 \u0645\u0648\u0636\u0648\u0639 \u0645\u0648\u0627\u062f (<\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"FA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u06f4\u06f8)<\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u060c (<\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"FA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u06f5\u06f0) <\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0648 (<\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"FA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u06f5\u06f1) <\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 (\u0645\u0635\u0648\u0628 <\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"FA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u06f1\u06f4\u06f0\u06f0\/\u06f0\u06f3\/\u06f0\u06f2)<\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0646\u0638\u0631 \u0628\u0647 \u0627\u06cc\u0646\u00ac\u06a9\u0647 \u0628\u0647 \u0645\u0648\u062c\u0628 \u0645\u0648\u0627\u062f (48)\u060c (50) \u0648 (51) \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u0635\u0648\u0628 1400\/03\/02 \u0645\u062c\u0644\u0633 \u0634\u0648\u0631\u0627\u06cc \u0627\u0633\u0644\u0627\u0645\u06cc\u060c \u0645\u0641\u0627\u062f \u0645\u0648\u0627\u062f (238) \u060c (244) \u0648 (251) \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u00ac\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 ( \u0645\u0635\u0648\u0628 \u0627\u0633\u0641\u0646\u062f 1366 \u0648 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0648 \u0627\u0644\u062d\u0627\u0642\u0627\u062a \u0628\u0639\u062f\u06cc) \u0627\u0635\u0644\u0627\u062d \u0648 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e 1400\/10\/13 \u0644\u0627\u0632\u0645\u200c\u0627\u0644\u0627\u062c\u0631\u0627 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f\u060c \u0628\u062f\u06cc\u0646 \u0648\u0633\u06cc\u0644\u0647 \u0645\u0648\u0627\u0631\u062f \u0630\u06cc\u0644 \u0631\u0627 \u0645\u0642\u0631\u0631 \u0645\u06cc \u062f\u0627\u0631\u062f<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">:<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">1<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">&#8211; \u06a9\u0644\u06cc\u0647 \u0627\u0639\u062a\u0631\u0627\u0636\u0627\u062a\u06cc \u06a9\u0647 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e \u0644\u0627\u0632\u0645\u200c\u0627\u0644\u0627\u062c\u0631\u0627 \u0634\u062f\u0646 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0648 \u062f\u0631 \u0645\u0647\u0644\u062a \u0645\u0642\u0631\u0631 \u062a\u0633\u0644\u06cc\u0645 \u0627\u062f\u0627\u0631\u0647 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0630\u06cc\u200c\u0631\u0628\u0637 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0642\u0627\u0628\u0644 \u0631\u0633\u06cc\u062f\u06af\u06cc \u0645\u062c\u062f\u062f \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0645\u0641\u0627\u062f <\/span><a href=\"https:\/\/karmento.ir\/blog\/%D9%85%D8%A7%D8%AF%D9%87-238-%D9%82%D8%A7%D9%86%D9%88%D9%86-%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA-%D9%85%D8%B3%D8%AA%D9%82%DB%8C%D9%85\/\"><span style=\"color: #2980b9;\">\u0645\u0627\u062f\u0647 238 \u0627\u0635\u0644\u0627\u062d\u06cc \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/span><\/a><span style=\"color: #151a1e;\"> \u0648 \u062f\u0633\u062a\u0648\u0631\u0627\u0644\u0639\u0645\u0644 \u0627\u062c\u0631\u0627\u06cc\u06cc \u0622\u0646 \u0645\u06cc\u200c\u0628\u0627\u0634\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0627\u0639\u062a\u0631\u0627\u0636\u0627\u062a \u0628\u0647 \u0639\u0645\u0644 \u0622\u0645\u062f\u0647\u060c \u0642\u0628\u0644 \u0627\u0632 \u0627\u062c\u0631\u0627\u06cc \u0642\u0627\u0646\u0648\u0646 \u0645\u0630\u06a9\u0648\u0631 \u062a\u0627\u0628\u0639 \u0645\u0642\u0631\u0631\u0627\u062a \u0632\u0645\u0627\u0646 \u0627\u0639\u062a\u0631\u0627\u0636 (\u062d\u0633\u0628 \u0645\u0648\u0631\u062f \u0645\u0627\u062f\u0647 238 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 \u0627\u0635\u0644\u0627\u062d\u06cc\u0647 1394\/04\/31\u00a0 \u0648 \u0642\u0633\u0645\u062a \u0627\u062e\u06cc\u0631 <\/span><a href=\"https:\/\/karmento.ir\/blog\/%D9%85%D8%A7%D8%AF%D9%87-29-%D9%82%D8%A7%D9%86%D9%88%D9%86-%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA-%D8%A7%D8%B1%D8%B2%D8%B4-%D8%A7%D9%81%D8%B2%D9%88%D8%AF%D9%87\/\"><span style=\"color: #2980b9;\">\u0645\u0627\u062f\u0647 29 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647<\/span><\/a><span style=\"color: #151a1e;\"> \u0645\u0635\u0648\u0628 \u0633\u0627\u0644 1387) \u0645\u06cc\u200c\u0628\u0627\u0634\u0646\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">2<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">&#8211;\u00a0 \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062a\u0633\u0631\u06cc \u0645\u0627\u062f\u0647 (238) \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 \u0628\u0647 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0628\u0647 \u0645\u0648\u062c\u0628 \u0645\u0627\u062f\u0647 (48) \u0642\u0627\u0646\u0648\u0646 \u0645\u0630\u06a9\u0648\u0631 \u0645\u0635\u0648\u0628 1400\/03\/02\u060c \u0645\u0647\u0644\u062a \u0627\u0639\u062a\u0631\u0627\u0636 \u0628\u0647 \u0627\u0648\u0631\u0627\u0642 \u0645\u0637\u0627\u0644\u0628\u0647 \u06cc\u0627 \u0627\u0633\u062a\u0631\u062f\u0627\u062f \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u06a9\u0647 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e 1400\/10\/13 \u0628\u0647 \u0628\u0639\u062f \u0627\u0628\u0644\u0627\u063a \u0645\u06cc\u00ac\u0634\u0648\u062f\u060c \u0633\u06cc(30) \u0631\u0648\u0632 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e \u0627\u0628\u0644\u0627\u063a \u0627\u0648\u0631\u0627\u0642 \u0645\u0630\u06a9\u0648\u0631 \u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">3<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">&#8211; \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062a\u063a\u06cc\u06cc\u0631 \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0647\u06cc\u0623\u062a\u00ac\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u0647 \u0634\u0631\u062d \u0645\u0642\u0631\u0631\u0627\u062a <\/span><a href=\"https:\/\/karmento.ir\/blog\/%D9%85%D8%A7%D8%AF%D9%87-244-%D9%82%D8%A7%D9%86%D9%88%D9%86-%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA-%D9%85%D8%B3%D8%AA%D9%82%DB%8C%D9%85\/\"><span style=\"color: #2980b9;\">\u0645\u0627\u062f\u0647 (244) \u0627\u0635\u0644\u0627\u062d\u06cc \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/span><\/a><span style=\"color: #151a1e;\"> \u0648 \u0646\u0638\u0631 \u0628\u0647 \u0644\u0627\u0632\u0645 \u0627\u0644\u0627\u062c\u0631\u0627 \u0634\u062f\u0646 \u0627\u062d\u06a9\u0627\u0645 \u0645\u0642\u0631\u0631 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647 \u0648 \u062a\u0628\u0635\u0631\u0647\u200c\u0647\u0627\u06cc \u0622\u0646 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e 1400\/10\/13\u060c \u062f\u0631 \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u0633\u0627\u062e\u062a\u0627\u0631 \u062c\u062f\u06cc\u062f \u0647\u06cc\u0623\u062a\u200c \u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u0647 \u0645\u0648\u062c\u0628 \u0627\u062d\u06a9\u0627\u0645 \u0635\u0627\u062f\u0631\u0647 \u062a\u0648\u0633\u0637 \u0645\u0631\u06a9\u0632 \u062f\u0627\u062f\u0631\u0633\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0634\u06a9\u0644 \u0646\u06af\u0631\u0641\u062a\u0647 \u0627\u0633\u062a\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a \u0647\u06cc\u0623\u062a\u200c\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u0648\u0638\u0641\u0646\u062f \u062f\u0631\u062e\u0635\u0648\u0635 \u067e\u0631\u0648\u0646\u062f\u0647\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0622\u0646\u0647\u0627 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e 1400\/10\/13 \u0628\u0647 \u0628\u0639\u062f \u062a\u0639\u06cc\u06cc\u0646 \u0648\u0642\u062a \u062c\u0644\u0633\u0647 \u062f\u0627\u062f\u0631\u0633\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0628\u0627 \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0645\u0631\u06a9\u0632 \u0645\u0630\u06a9\u0648\u0631\u060c \u0646\u0633\u0628\u062a \u0628\u0647 \u062a\u062c\u062f\u06cc\u062f \u062f\u0639\u0648\u062a \u0627\u0632 \u0645\u0648\u062f\u06cc \u0648 \u0628\u0631\u06af\u0632\u0627\u0631\u06cc \u062c\u0644\u0633\u0647 \u0647\u06cc\u0623\u062a \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062f\u0631 \u0686\u0627\u0631\u0686\u0648\u0628 \u062a\u0634\u06a9\u06cc\u0644\u0627\u062a \u062c\u062f\u06cc\u062f \u0645\u0631\u06a9\u0632 \u062f\u0627\u062f\u0631\u0633\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0642\u062f\u0627\u0645 \u0648 \u0645\u0631\u0627\u062a\u0628 \u0639\u062f\u0645 \u062a\u0634\u06a9\u06cc\u0644 \u062c\u0644\u0633\u0647 \u0647\u06cc\u0623\u062a \u0631\u0627 \u0628\u0647 \u0627\u0637\u0644\u0627\u0639 \u0645\u0648\u062f\u06cc \u0630\u06cc\u200c\u0631\u0628\u0637 \u0628\u0631\u0633\u0627\u0646\u0646\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">-4\u0628\u0647 \u0645\u0648\u062c\u0628 \u0645\u0627\u062f\u0647 (251) \u0627\u0635\u0644\u0627\u062d\u06cc \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645\u060c \u0645\u0647\u0644\u062a \u0627\u0639\u062a\u0631\u0627\u0636 \u0628\u0647 \u0622\u0631\u0627\u06cc \u0642\u0637\u0639\u06cc \u0647\u06cc\u0623\u062a\u200c\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062a\u062c\u062f\u06cc\u062f \u0646\u0638\u0631\u060c \u062f\u0648 (2) \u0645\u0627\u0647 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e \u0627\u0628\u0644\u0627\u063a \u0631\u0627\u06cc \u0645\u0630\u06a9\u0648\u0631 \u0645\u06cc \u0628\u0627\u0634\u062f. \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0645\u0627\u062f\u0647\u060c \u0645\u0648\u062f\u06cc \u06cc\u0627 \u062f\u0627\u062f\u0633\u062a\u0627\u0646 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u0622\u0631\u0627\u06cc \u0645\u0630\u06a9\u0648\u0631 \u0628\u0647 \u0627\u0633\u062a\u0646\u0627\u062f \u0639\u062f\u0645 \u0631\u0639\u0627\u06cc\u062a \u0642\u0648\u0627\u0646\u06cc\u0646 \u0648 \u0645\u0642\u0631\u0631\u0627\u062a \u0645\u0648\u0636\u0648\u0639\u0647 \u06cc\u0627 \u0646\u0642\u0635 \u0631\u0633\u06cc\u062f\u06af\u06cc\u060c \u0628\u0627 \u0627\u0639\u0644\u0627\u0645 \u062f\u0644\u0627\u06cc\u0644 \u06a9\u0627\u0641\u06cc \u0628\u0647 \u0634\u0648\u0631\u0627\u06cc \u0639\u0627\u0644\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0639\u062a\u0631\u0627\u0636 \u0648 \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u062a\u062c\u062f\u06cc\u062f \u0631\u0633\u06cc\u062f\u06af\u06cc \u0646\u0645\u0627\u06cc\u0646\u062f. \u062f\u0627\u062f\u0633\u062a\u0627\u0646 \u0627\u0646\u062a\u0638\u0627\u0645\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u062a\u0628\u0635\u0631\u0647 <a href=\"https:\/\/karmento.ir\/blog\/%D9%85%D8%A7%D8%AF%D9%87-263-%D9%82%D8%A7%D9%86%D9%88%D9%86-%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA-%D9%85%D8%B3%D8%AA%D9%82%DB%8C%D9%85\/\">\u0645\u0627\u062f\u0647 263 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/a><\/span><span style=\"color: #151a1e;\">\u00a0\u0645\u06cc \u062a\u0648\u0627\u0646\u062f \u0627\u062e\u062a\u06cc\u0627\u0631 \u0627\u0639\u062a\u0631\u0627\u0636 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062f\u0627\u062f\u06cc\u0627\u0631\u0627\u0646 \u062a\u0641\u0648\u06cc\u0636 \u0646\u0645\u0627\u06cc\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">-5\u0645\u0647\u0644\u062a \u062f\u0648 (2) \u0645\u0627\u0647\u0647 \u0627\u0639\u062a\u0631\u0627\u0636 \u0645\u0648\u0636\u0648\u0639 \u0645\u0627\u062f\u0647 (251) \u0627\u0635\u0644\u0627\u062d\u06cc \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645\u060c \u0635\u0631\u0641\u0627 \u0645\u0631\u0628\u0648\u0637 \u0628\u0647 \u0622\u0631\u0627\u06cc \u0635\u0627\u062f\u0631\u0647\u200c\u0627\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e\u00a0 1400\/10\/13 \u0627\u0628\u0644\u0627\u063a \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0622\u0631\u0627\u06cc \u0642\u0637\u0639\u06cc \u0647\u06cc\u0623\u062a\u200c\u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0647 \u0642\u0628\u0644 \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e \u0645\u0630\u06a9\u0648\u0631 \u0627\u0628\u0644\u0627\u063a \u0634\u062f\u0647\u200c\u0627\u0646\u062f\u060c \u0628\u0647 \u0644\u062d\u0627\u0638 \u0627\u0639\u062a\u0631\u0627\u0636 \u06a9\u0645\u0627\u06a9\u0627\u0646 \u062a\u0627\u0628\u0639 \u0645\u0642\u0631\u0631\u0627\u062a <\/span><a href=\"https:\/\/karmento.ir\/blog\/%D9%85%D8%A7%D8%AF%D9%87-251-%D9%82%D8%A7%D9%86%D9%88%D9%86-%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA-%D9%85%D8%B3%D8%AA%D9%82%DB%8C%D9%85\/\"><span style=\"color: #2980b9;\">\u0645\u0627\u062f\u0647 (251) \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/span><\/a><span style=\"color: #151a1e;\"> \u0627\u0635\u0644\u0627\u062d\u06cc\u0647 \u0645\u0635\u0648\u0628 1394\/04\/31 \u0645\u06cc \u0628\u0627\u0634\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0622\u0631\u0627\u06cc \u0642\u0637\u0639\u06cc \u0647\u06cc\u0623\u062a \u0647\u0627\u06cc \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06cc\u06a9 \u0645\u0631\u062d\u0644\u0647\u200c\u0627\u06cc \u0627\u0632 \u062a\u0627\u0631\u06cc\u062e \u0644\u0627\u0632\u0645 \u0627\u0644\u0627\u062c\u0631\u0627 \u0634\u062f\u0646 \u0642\u0627\u0646\u0648\u0646 \u0645\u0630\u06a9\u0648\u0631\u060c \u0642\u0627\u0628\u0644 \u0627\u0639\u062a\u0631\u0627\u0636 \u062f\u0631 \u0634\u0648\u0631\u0627\u06cc \u0639\u0627\u0644\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0646\u0645\u06cc \u0628\u0627\u0634\u0646\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0646\u0638\u0627\u0631\u062a\u00a0 \u0628\u0631 \u062d\u0633\u0646 \u0627\u062c\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0628\u062e\u0634\u0646\u0627\u0645\u0647\u060c \u0628\u0631 \u0639\u0647\u062f\u0647 \u062f\u0627\u062f\u0633\u062a\u0627\u0646\u06cc \u0627\u0646\u062a\u0638\u0627\u0645\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u06cc \u0628\u0627\u0634\u062f<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u062f\u0627\u0648\u062f \u0645\u0646\u0638\u0648\u0631<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0631\u0626\u06cc\u0633 \u06a9\u0644 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0634\u0645\u0627\u0631\u0647:200\/1400\/67<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><strong><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0627\u0628\u0644\u0627\u063a \u0635\u0648\u0631\u062a\u062c\u0644\u0633\u0647 \u0634\u0645\u0627\u0631\u0647 <\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"FA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u06f8-\u06f2\u06f0\u06f1<\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\"> \u0645\u0648\u0631\u062e <\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"FA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u06f1\u06f3\u06f9\u06f7\/\u06f0\u06f4\/\u06f2\u06f6<\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\"> \u0634\u0648\u0631\u0627\u06cc \u0639\u0627\u0644\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062f\u0631\u062e\u0635\u0648\u0635 \u0645\u0633\u0627\u0626\u0644 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0642\u0631\u0627\u0631\u062f\u0627\u062f\u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647 \u0633\u0627\u0632\u06cc \u0627\u0631\u0627\u0636\u06cc \u0648 \u0645\u062d\u0648\u0637\u0647 \u0633\u0627\u0632\u06cc \u067e\u0631\u0648\u0698\u0647 \u0647\u0627\u06cc \u0645\u0633\u06a9\u0646 \u0645\u0647\u0631<\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0628\u0647 \u067e\u06cc\u0648\u0633\u062a \u0631\u0623\u06cc \u0627\u06a9\u062b\u0631\u06cc\u062a \u0627\u0639\u0636\u0627\u06cc \u0634\u0648\u0631\u0627\u06cc \u0639\u0627\u0644\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc<\/span><\/span><\/span><\/span> <\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0645\u0648\u0636\u0648\u0639 \u0635\u0648\u0631\u062a\u062c\u0644\u0633\u0647 \u0634\u0645\u0627\u0631\u0647 8-201 \u0645\u0648\u0631\u062e 1397\/04\/26 \u06a9\u0647 \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0628\u0646\u062f 3 \u0645\u0627\u062f\u0647 255 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 \u062f\u0631 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u0645\u0633\u0627\u0626\u0644 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0642\u0631\u0627\u0631\u062f\u0627\u062f\u0647\u0627\u06cc \u0622\u0645\u0627\u062f\u0647 \u0633\u0627\u0632\u06cc \u0627\u0631\u0627\u0636\u06cc \u0648 \u0645\u062d\u0648\u0637\u0647 \u0633\u0627\u0632\u06cc \u067e\u0631\u0648\u0698\u0647 \u0647\u0627\u06cc \u0645\u0633\u06a9\u0646 \u0645\u0647\u0631 \u0635\u0627\u062f\u0631 \u0648 \u0628\u0647 \u062a\u0646\u0641\u06cc\u0630 \u0645\u0642\u0627\u0645 \u0639\u0627\u0644\u06cc \u0648\u0632\u0627\u0631\u062a \u0631\u0633\u06cc\u062f\u0647 \u0627\u0633\u062a\u060c \u062c\u0647\u062a \u0627\u0637\u0644\u0627\u0639 \u0648 \u0627\u0642\u062f\u0627\u0645 \u0644\u0627\u0632\u0645 \u0627\u0628\u0644\u0627\u063a \u0645\u06cc \u06af\u0631\u062f\u062f<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0646\u0627\u062f\u0631 \u062c\u0646\u062a\u06cc<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0645\u0639\u0627\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0634\u0645\u0627\u0631\u0647: 230\/97\/82<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><strong><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0627\u0628\u0644\u0627\u063a \u062c\u062f\u0648\u0644 \u0636\u0631\u0627\u06cc\u0628 \u062a\u0634\u062e\u06cc\u0635 \u062f\u0631\u0622\u0645\u062f \u0645\u0634\u0645\u0648\u0644 \u0645\u0627\u0644\u06cc\u0627\u062a \u0639\u0645\u0644\u06a9\u0631\u062f \u0633\u0627\u0644 <\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"FA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u06f1\u06f3\u06f9\u06f6<\/span><\/span><\/span><\/span><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\"> \u062c\u0647\u062a \u0627\u062c\u0631\u0627 \u062f\u0631 \u0627\u062f\u0627\u0631\u0627\u062a \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u0633\u062a\u0642\u0631 \u062f\u0631 \u0634\u0647\u0631\u0647\u0627\u06cc \u062a\u0647\u0631\u0627\u0646\u060c \u0634\u0645\u06cc\u0631\u0627\u0646\u0627\u062a \u0648 \u0631\u06cc (\u0628\u0647 \u0627\u0633\u062a\u062b\u0646\u0627\u06cc \u0634\u0647\u0631\u0633\u062a\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0633\u062a\u0627\u0646 \u062a\u0647\u0631\u0627\u0646)<\/span><\/span><\/span><\/span><\/span><\/strong><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0628\u0647 \u0627\u0633\u062a\u0646\u0627\u062f \u0645\u0641\u0627\u062f \u0642\u0633\u0645\u062a \u0627\u062e\u06cc\u0631 \u062a\u0628\u0635\u0631\u0647 \u0645\u0627\u062f\u0647 97 \u0627\u0635\u0644\u0627\u062d\u06cc \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 \u0645\u0635\u0648\u0628 1394\/04\/31 \u0648 \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0645\u0642\u0631\u0631\u0627\u062a \u0628\u0646\u062f (\u0627\u0644\u0641) \u0645\u0627\u062f\u0647 154 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 \u0645\u0635\u0648\u0628 1380\/11\/27\u060c \u0628\u0647 \u067e\u06cc\u0648\u0633\u062a \u06cc\u06a9 \u0639\u062f\u062f \u0644\u0648\u062d \u0641\u0634\u0631\u062f\u0647<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\"> (CD) \u0645\u062c\u0645\u0648\u0639\u0647 \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0633\u0627\u0644 1396 \u062d\u0648\u0632\u0647 \u062a\u0647\u0631\u0627\u0646 \u0645\u0635\u0648\u0628 \u06a9\u0645\u06cc\u0633\u06cc\u0648\u0646 \u062a\u0639\u06cc\u06cc\u0646 \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc\u060c \u0628\u0647 \u0627\u0646\u0636\u0645\u0627\u0645 \u0641\u0647\u0631\u0633\u062a \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0648 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0633\u0627\u0644 1396 \u0646\u0633\u0628\u062a \u0628\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0633\u0627\u0644 1395 ( \u062f\u0631 \u0642\u0627\u0644\u0628 256 \u0631\u062f\u06cc\u0641 \u0648 50 \u0635\u0641\u062d\u0647 ) \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0627\u062c\u0631\u0627 \u062f\u0631 \u0627\u062f\u0627\u0631\u0627\u062a \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062a\u0627\u0628\u0639\u0647 \u0645\u0633\u062a\u0642\u0631 \u062f\u0631 \u0634\u0647\u0631\u0647\u0627\u06cc \u062a\u0647\u0631\u0627\u0646\u060c \u0634\u0645\u06cc\u0631\u0627\u0646\u0627\u062a \u0648 \u0631\u06cc\u060c \u0627\u0628\u0644\u0627\u063a \u0645\u06cc\u200c\u06af\u0631\u062f\u062f. \u0636\u0645\u0646\u0627 \u062f\u0631 \u062e\u0635\u0648\u0635 \u0645\u062c\u0645\u0648\u0639\u0647 \u06cc\u0627\u062f \u0634\u062f\u0647\u060c \u062a\u0648\u062c\u0647 \u0627\u062f\u0627\u0631\u0627\u062a \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0648 \u0645\u0631\u0627\u062c\u0639 \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0631\u0627 \u0628\u0647 \u0646\u06a9\u0627\u062a \u0630\u06cc\u0644 \u062c\u0644\u0628 \u0648 \u0645\u0642\u0631\u0631 \u0645\u06cc\u200c\u062f\u0627\u0631\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">1<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">&#8211; \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062a\u0639\u062f\u06cc\u0644 \u0648 \u0627\u0635\u0644\u0627\u062d \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u06cc\u0634 \u0627\u0632 370 \u0645\u0648\u0631\u062f \u0627\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc (\u0634\u0627\u0645\u0644 130 \u0642\u0644\u0645 \u0627\u0632 \u06a9\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06cc\u060c 151 \u0642\u0644\u0645 \u0627\u0632 \u06a9\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u0639\u0645\u062f\u0647 \u0641\u0631\u0648\u0634\u06cc \u06a9\u0627\u0644\u0627\u0647\u0627\u060c 47 \u0642\u0644\u0645 \u0627\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u062e\u0631\u062f\u0647 \u0641\u0631\u0648\u0634\u06cc\u060c 12 \u0642\u0644\u0645 \u0627\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u0648\u0627\u0631\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u0646\u0648\u0627\u0639 \u06a9\u0627\u0644\u0627\u0647\u0627 \u0648 32 \u0642\u0644\u0645 \u0627\u0632 \u0641\u0639\u0627\u0644\u06cc\u062a\u0647\u0627\u06cc \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u0646\u062f\u06af\u0627\u0646 \u062e\u062f\u0645\u0627\u062a \u067e\u0632\u0634\u06a9\u06cc \u0648 \u063a\u06cc\u0631 \u067e\u0632\u0634\u06a9\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06cc\u062c\u0627\u062f \u0628\u0631\u062e\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u06cc \u062c\u062f\u06cc\u062f) \u062a\u0648\u0633\u0637 \u06a9\u0645\u06cc\u0633\u06cc\u0648\u0646 \u06cc\u0627\u062f \u0634\u062f\u0647 \u062f\u0631 \u0631\u0627\u0633\u062a\u0627\u06cc \u062a\u062d\u0642\u0642 \u0627\u0647\u062f\u0627\u0641 \u0633\u06cc\u0627\u0633\u062a\u0647\u0627\u06cc \u06a9\u0644\u06cc \u0627\u0642\u062a\u0635\u0627\u062f \u0645\u0642\u0627\u0648\u0645\u062a\u06cc\u060c \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u062a\u0648\u0644\u06cc\u062f \u0648 \u06a9\u0627\u0644\u0627\u06cc \u0627\u06cc\u0631\u0627\u0646\u06cc \u0648 \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0634\u0641\u0627\u0641\u06cc\u062a \u062f\u0631 \u0641\u0639\u0627\u0644\u06cc\u062a\u00ac\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062f\u0631 \u0627\u062c\u0631\u0627\u06cc \u0645\u0642\u0631\u0631\u0627\u062a \u0645\u0648\u0627\u062f 169 \u0648 169 \u0645\u06a9\u0631\u0631 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 \u0645\u0635\u0648\u0628 1394\/04\/31; \u0636\u0645\u0646 \u062a\u0623\u06a9\u06cc\u062f \u0628\u0631 \u0644\u0632\u0648\u0645 \u062f\u0642\u062a \u0646\u0638\u0631\u06a9\u0627\u0645\u0644 \u0627\u062f\u0627\u0631\u0627\u062a \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062f\u0631 \u0631\u0639\u0627\u06cc\u062a \u0646\u06a9\u0627\u062a \u0648 \u0636\u0648\u0627\u0628\u0637 \u0627\u062c\u0631\u0627\u0626\u06cc \u0645\u0646\u062f\u0631\u062c \u062f\u0631 \u0645\u0642\u062f\u0645\u0647 \u0645\u062c\u0645\u0648\u0639\u0647 \u0645\u0630\u06a9\u0648\u0631 \u0648 \u0646\u06cc\u0632 \u0627\u0633\u062a\u062e\u0631\u0627\u062c \u0648 \u0627\u0639\u0645\u0627\u0644 \u062f\u0642\u06cc\u0642 \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a \u0647\u0627\u060c \u0627\u062f\u0627\u0631\u0627\u062a \u0645\u0632\u0628\u0648\u0631 \u0645\u0648\u0638\u0641\u0646\u062f \u0636\u0645\u0646 \u0631\u0639\u0627\u06cc\u062a \u06a9\u0644\u06cc\u0647 \u062c\u0648\u0627\u0646\u0628 \u0627\u0645\u0631 \u0648 \u062a\u0648\u062c\u0647 \u06a9\u0627\u0645\u0644 \u0628\u0647 \u062f\u0644\u0627\u06cc\u0644 \u0648 \u0627\u0633\u0646\u0627\u062f \u0648 \u0645\u062f\u0627\u0631\u06a9 \u0645\u0648\u062f\u06cc \u0648 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u0647\u0645\u06cc\u062a \u0645\u0648\u0636\u0648\u0639 \u0627\u0632 \u0637\u0631\u06cc\u0642 \u062a\u062d\u0642\u06cc\u0642 \u0648 \u0631\u0633\u06cc\u062f\u06af\u06cc \u0648 \u0646\u0647 \u0635\u0631\u0641\u0627 \u0647\u062f\u0641 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f\u0646 \u0636\u0631\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc\u060c \u0646\u0633\u0628\u062a \u0628\u0647 \u062a\u0639\u06cc\u06cc\u0646 \u062f\u0631\u0622\u0645\u062f \u0645\u0634\u0645\u0648\u0644 \u0645\u0627\u0644\u06cc\u0627\u062a \u0648\u0627\u0642\u0639\u06cc \u0648 \u0645\u0627\u0644\u06cc\u0627\u062a \u0639\u0627\u062f\u0644\u0627\u0646\u0647 \u0645\u0648\u062f\u06cc \u0627\u0642\u062f\u0627\u0645 \u0648 \u062d\u062a\u06cc \u0627\u0644\u0627\u0645\u06a9\u0627\u0646 \u0627\u0632 \u0627\u0639\u0644\u0627\u0645 \u0646\u0638\u0631 \u063a\u06cc\u0631\u06a9\u0627\u0631\u0634\u0646\u0640\u0627\u0633\u06cc \u0648 \u06cc\u0627 \u0627\u0631\u0627\u0626\u0640\u0647 \u062f\u0644\u0627\u06cc\u0644 \u0636\u0639\u06cc\u0640\u0641 \u062f\u0631 \u0627\u0645\u0648\u0631 \u06af\u0640\u0632\u0627\u0631\u0634\u06af\u0631\u06cc \u0645\u0627\u0644\u06cc\u0640\u0627\u062a\u06cc \u062e\u0640\u0648\u062f\u062f\u0627\u0631\u06cc \u0646\u0645\u0627\u06cc\u0646\u0640\u062f. \u0636\u0640\u0631\u0648\u0631\u06cc \u0627\u0633\u062a \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0641\u0640\u0648\u0642 \u0628\u0647 \u0646\u062d\u0640\u0648\u06cc \u0645\u062f\u06cc\u0631\u06cc\u062a \u0634\u0640\u0648\u062f \u06a9\u0640\u0647 \u0645\u0648\u062f\u06cc\u0627\u0646 \u0645\u062d\u0640\u062a\u0640\u0631\u0645 \u0645\u0627\u0644\u06cc\u0640\u0640\u0627\u062a\u06cc \u0628\u0640\u0647 \u0631\u0639\u0627\u06cc\u062a \u0627\u0646\u0636\u0628\u0627\u0637 \u0645\u0627\u0644\u06cc \u0648 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0648 \u0627\u0631\u0627\u0626\u0647 \u0628\u0647 \u0645\u0648\u0642\u0639 \u062f\u0641\u0627\u062a\u0631 \u0648 \u0627\u0633\u0646\u0627\u062f \u0648 \u0645\u062f\u0627\u0631\u06a9 \u062a\u0631\u063a\u06cc\u0628 \u0648 \u0645\u0648\u062c\u0628\u0627\u062a \u0631\u0636\u0640\u0627\u06cc\u0640\u062a\u060c \u0627\u0639\u062a\u0640\u0645\u0627\u062f \u0648 \u062a\u0634\u0640\u0648\u06cc\u0642 \u0622\u0646\u0627\u0646 \u0628\u0647 \u0627\u0646\u062c\u0627\u0645 \u062a\u06a9\u0627\u0644\u06cc\u0641 \u0642\u0627\u0646\u0648\u0646\u06cc \u0648 \u0632\u0645\u06cc\u0646\u0647\u00ac\u0647\u0627\u06cc \u06af\u0633\u062a\u0631\u0634 \u062a\u0634\u062e\u06cc\u0635 \u0645\u0627\u0644\u06cc\u0627\u062a \u0645\u0633\u062a\u0646\u062f \u0628\u0647 \u0627\u0633\u0646\u0627\u062f \u0648 \u0645\u062f\u0627\u0631\u06a9 \u0644\u0627\u0632\u0645 \u0648 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0648\u0627\u0642\u0639\u06cc\u0627\u062a \u0631\u0627 \u0641\u0631\u0627\u0647\u0645 \u0646\u0645\u0627\u06cc\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">2<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">&#8211; \u0636\u0645\u0646 \u062a\u0623\u06a9\u06cc\u062f \u0628\u0631 \u0644\u0632\u0648\u0645 \u062a\u0648\u062c\u0647 \u0646\u0645\u0627\u06cc\u0646\u0640\u062f\u06af\u0627\u0646 \u0647\u0640\u06cc\u0623\u062a\u200c\u0647\u0627\u06cc \u062d\u0640\u0644 \u0627\u062e\u062a\u0640\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc(\u0645\u0648\u0636\u0648\u0639 \u062a\u0628\u0635\u0631\u0647 3 \u0645\u0627\u062f\u0647 154\u0642.\u0645.\u0645) \u0628\u0647 \u0646\u0640\u062d\u0648\u0647 \u0627\u062c\u0640\u0631\u0627\u06cc \u0635\u062d\u06cc\u062d \u062d\u06a9\u0645 \u0642\u0633\u0645\u062a \u0627\u062e\u06cc\u0631 \u0645\u0642\u0640\u0631\u0631\u0627\u062a \u06cc\u0627\u062f \u0634\u0640\u062f\u0647 \u0645\u0628\u0646\u06cc \u0628\u0640\u0631 \u062a\u0639\u06cc\u06cc\u0646 \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u0634\u0627\u063a\u0644 \u0645\u0634\u0627\u0628\u0647\u060c \u0627\u062f\u0627\u0631\u0627\u062a \u06a9\u0640\u0644 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u0640\u06a9\u0644\u0641\u0646\u062f \u0641\u0640\u0647\u0631\u0633\u062a \u0645\u0648\u0627\u0631\u062f\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u062c\u0640\u0631\u0627\u06cc \u0645\u0642\u0631\u0631\u0627\u062a \u062a\u0628\u0635\u0631\u0647 3 \u0645\u0627\u062f\u0647 154 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627 \u062a\u0639\u06cc\u06cc\u0646 \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0622\u0646\u0647\u0627 \u0628\u0647 \u0647\u06cc\u0623\u062a \u062d\u0644 \u0627\u062e\u062a\u0644\u0627\u0641 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u062d\u0627\u0644\u0647 \u0645\u06cc\u200c\u06af\u0631\u062f\u062f \u0631\u0627 \u0628\u0647 \u0627\u0646\u0636\u0645\u0627\u0645 \u062a\u0635\u0627\u0648\u06cc\u0631 \u0622\u0631\u0627\u0621 \u0647\u06cc\u0623\u062a\u00ac\u0647\u0627\u06cc \u0645\u0632\u0628\u0648\u0631\u060c \u0647\u0631 \u0633\u0647 \u0645\u0627\u0647 \u06cc\u06a9\u0628\u0627\u0631 \u0628\u0647 \u062f\u0641\u062a\u0631 \u067e\u0698\u0648\u0647\u0634 \u0648 \u0628\u0631\u0646\u0627\u0645\u0647 \u0631\u06cc\u0632\u06cc \u0627\u0631\u0633\u0627\u0644 \u0646\u0645\u0627\u06cc\u0646\u062f.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0645\u0632\u06cc\u062f \u0627\u0637\u0644\u0627\u0639\u060c \u06a9\u062a\u0627\u0628 \u0636\u0631\u0627\u06cc\u0628 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u0633\u0627\u0644 1396\u067e\u0633 \u0627\u0632 \u0627\u062a\u0645\u0627\u0645 \u0645\u0631\u0627\u062d\u0644 \u0686\u0627\u067e\u060c \u0628\u0647 \u062a\u0639\u062f\u0627\u062f \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u0627\u062f\u0627\u0631\u0627\u062a \u06a9\u0644 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062a\u0627\u0628\u0639\u0647\u060c \u0627\u0631\u0633\u0627\u0644 \u062e\u0648\u0627\u0647\u062f \u0634\u062f<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0645\u062f\u06cc\u0631\u0627\u0646 \u06a9\u0644 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc\u060c \u0645\u0633\u0626\u0648\u0644 \u062d\u0633\u0646 \u0627\u062c\u0631\u0627\u06cc \u0645\u0641\u0627\u062f \u0627\u06cc\u0646 \u0628\u062e\u0634\u0646\u0627\u0645\u0647 \u0648 \u0627\u0639\u0644\u0627\u0645 \u0645\u0648\u0627\u0631\u062f \u062a\u062e\u0644\u0641 \u0627\u0632 \u0622\u0646 \u0628\u0647 \u062f\u0627\u062f\u0633\u062a\u0627\u0646\u06cc \u0627\u0646\u062a\u0638\u0627\u0645\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0645\u06cc \u00ac\u0628\u0627\u0634\u0646\u062f<\/span><\/span><\/span><\/span><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">.<\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0633\u06cc\u062f \u06a9\u0627\u0645\u0644 \u062a\u0642\u0648\u06cc \u0646\u0698\u0627\u062f<\/span><\/span><\/span><\/span><\/span><\/p>\n<p style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"line-height: 107%;\"><span dir=\"RTL\" lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u0631\u0626\u06cc\u0633 \u06a9\u0644 \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631<\/span><\/span><\/span><\/span><\/span><\/p>\n<p dir=\"RTL\" style=\"margin-bottom: 11px; text-align: justify;\"><span style=\"direction: rtl;\"><span style=\"unicode-bidi: embed;\"><span style=\"line-height: 107%;\"><span lang=\"AR-SA\"><span style=\"background: white;\"><span style=\"line-height: 107%;\"><span style=\"color: #151a1e;\">\u00a0\u0634\u0645\u0627\u0631\u0647:200\/97\/99<\/span><\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645<\/p>\n","protected":false},"author":13,"featured_media":23034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[267],"tags":[],"class_list":["post-23033","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-267"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 + \u0628\u062e\u0634\u0646\u0627\u0645\u0647 \u0648 \u062a\u062d\u0644\u06cc\u0644 \u062a\u062e\u0635\u0635\u06cc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/karmento.ir\/blog\/\u0645\u0627\u062f\u0647-244-\u0642\u0627\u0646\u0648\u0646-\u0645\u0627\u0644\u06cc\u0627\u062a-\u0645\u0633\u062a\u0642\u06cc\u0645\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645\" \/>\n<meta property=\"og:description\" content=\"\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645\" \/>\n<meta property=\"og:url\" content=\"https:\/\/karmento.ir\/blog\/\u0645\u0627\u062f\u0647-244-\u0642\u0627\u0646\u0648\u0646-\u0645\u0627\u0644\u06cc\u0627\u062a-\u0645\u0633\u062a\u0642\u06cc\u0645\/\" \/>\n<meta property=\"og:site_name\" content=\"\u06a9\u0627\u0631\u0645\u0646\u062a\u0648\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-21T13:29:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T10:35:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/karmento.ir\/blog\/wp-content\/uploads\/images\/2022\/33\/750_199902244.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1\" \/>\n\t<meta property=\"og:image:height\" content=\"1\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Niloofar Zamani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637\" \/>\n\t<meta name=\"twitter:data1\" content=\"Niloofar Zamani\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 \u062f\u0642\u06cc\u0642\u0647\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/\"},\"author\":{\"name\":\"Niloofar Zamani\",\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/#\\\/schema\\\/person\\\/0bf55b936876b93c11e0d7bb26e210ec\"},\"headline\":\"\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645\",\"datePublished\":\"2022-08-21T13:29:58+00:00\",\"dateModified\":\"2024-09-20T10:35:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/\"},\"wordCount\":25,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/wp-content\\\/uploads\\\/images\\\/2022\\\/33\\\/750_199902244.jpg\",\"articleSection\":[\"\u0645\u0627\u0644\u06cc \u0648 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc\"],\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/\",\"url\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/\",\"name\":\"\u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 + \u0628\u062e\u0634\u0646\u0627\u0645\u0647 \u0648 \u062a\u062d\u0644\u06cc\u0644 \u062a\u062e\u0635\u0635\u06cc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/wp-content\\\/uploads\\\/images\\\/2022\\\/33\\\/750_199902244.jpg\",\"datePublished\":\"2022-08-21T13:29:58+00:00\",\"dateModified\":\"2024-09-20T10:35:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/#\\\/schema\\\/person\\\/0bf55b936876b93c11e0d7bb26e210ec\"},\"inLanguage\":\"fa-IR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\\\/#primaryimage\",\"url\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/wp-content\\\/uploads\\\/images\\\/2022\\\/33\\\/750_199902244.jpg\",\"contentUrl\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/wp-content\\\/uploads\\\/images\\\/2022\\\/33\\\/750_199902244.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/\",\"name\":\"\u06a9\u0627\u0631\u0645\u0646\u062a\u0648\",\"description\":\"\",\"alternateName\":\"\u06a9\u0627\u0631\u0645\u0646\u062a\u0648\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/#\\\/schema\\\/person\\\/0bf55b936876b93c11e0d7bb26e210ec\",\"name\":\"Niloofar Zamani\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3068213b58f0a4dfcf6f92653ba666edb8385665b9168848d650cd30cac1f03b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3068213b58f0a4dfcf6f92653ba666edb8385665b9168848d650cd30cac1f03b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3068213b58f0a4dfcf6f92653ba666edb8385665b9168848d650cd30cac1f03b?s=96&d=mm&r=g\",\"caption\":\"Niloofar Zamani\"},\"url\":\"https:\\\/\\\/karmento.ir\\\/blog\\\/author\\\/niloofarzamani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 + \u0628\u062e\u0634\u0646\u0627\u0645\u0647 \u0648 \u062a\u062d\u0644\u06cc\u0644 \u062a\u062e\u0635\u0635\u06cc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/karmento.ir\/blog\/\u0645\u0627\u062f\u0647-244-\u0642\u0627\u0646\u0648\u0646-\u0645\u0627\u0644\u06cc\u0627\u062a-\u0645\u0633\u062a\u0642\u06cc\u0645\/","og_locale":"fa_IR","og_type":"article","og_title":"\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645","og_description":"\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645","og_url":"https:\/\/karmento.ir\/blog\/\u0645\u0627\u062f\u0647-244-\u0642\u0627\u0646\u0648\u0646-\u0645\u0627\u0644\u06cc\u0627\u062a-\u0645\u0633\u062a\u0642\u06cc\u0645\/","og_site_name":"\u06a9\u0627\u0631\u0645\u0646\u062a\u0648","article_published_time":"2022-08-21T13:29:58+00:00","article_modified_time":"2024-09-20T10:35:11+00:00","og_image":[{"url":"https:\/\/karmento.ir\/blog\/wp-content\/uploads\/images\/2022\/33\/750_199902244.jpg","width":1,"height":1,"type":"image\/jpeg"}],"author":"Niloofar Zamani","twitter_card":"summary_large_image","twitter_misc":{"\u0646\u0648\u0634\u062a\u0647 \u0634\u062f\u0647 \u062a\u0648\u0633\u0637":"Niloofar Zamani","\u0632\u0645\u0627\u0646 \u062a\u062e\u0645\u06cc\u0646\u06cc \u0645\u0637\u0627\u0644\u0639\u0647":"13 \u062f\u0642\u06cc\u0642\u0647"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#article","isPartOf":{"@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/"},"author":{"name":"Niloofar Zamani","@id":"https:\/\/karmento.ir\/blog\/#\/schema\/person\/0bf55b936876b93c11e0d7bb26e210ec"},"headline":"\u0628\u0631\u0631\u0633\u06cc \u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645","datePublished":"2022-08-21T13:29:58+00:00","dateModified":"2024-09-20T10:35:11+00:00","mainEntityOfPage":{"@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/"},"wordCount":25,"commentCount":0,"image":{"@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#primaryimage"},"thumbnailUrl":"https:\/\/karmento.ir\/blog\/wp-content\/uploads\/images\/2022\/33\/750_199902244.jpg","articleSection":["\u0645\u0627\u0644\u06cc \u0648 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc"],"inLanguage":"fa-IR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/","url":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/","name":"\u0645\u0627\u062f\u0647 244 \u0642\u0627\u0646\u0648\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0627\u06cc \u0645\u0633\u062a\u0642\u06cc\u0645 + \u0628\u062e\u0634\u0646\u0627\u0645\u0647 \u0648 \u062a\u062d\u0644\u06cc\u0644 \u062a\u062e\u0635\u0635\u06cc","isPartOf":{"@id":"https:\/\/karmento.ir\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#primaryimage"},"image":{"@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#primaryimage"},"thumbnailUrl":"https:\/\/karmento.ir\/blog\/wp-content\/uploads\/images\/2022\/33\/750_199902244.jpg","datePublished":"2022-08-21T13:29:58+00:00","dateModified":"2024-09-20T10:35:11+00:00","author":{"@id":"https:\/\/karmento.ir\/blog\/#\/schema\/person\/0bf55b936876b93c11e0d7bb26e210ec"},"inLanguage":"fa-IR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/"]}]},{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/karmento.ir\/blog\/%d9%85%d8%a7%d8%af%d9%87-244-%d9%82%d8%a7%d9%86%d9%88%d9%86-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d9%85%d8%b3%d8%aa%d9%82%db%8c%d9%85\/#primaryimage","url":"https:\/\/karmento.ir\/blog\/wp-content\/uploads\/images\/2022\/33\/750_199902244.jpg","contentUrl":"https:\/\/karmento.ir\/blog\/wp-content\/uploads\/images\/2022\/33\/750_199902244.jpg"},{"@type":"WebSite","@id":"https:\/\/karmento.ir\/blog\/#website","url":"https:\/\/karmento.ir\/blog\/","name":"\u06a9\u0627\u0631\u0645\u0646\u062a\u0648","description":"","alternateName":"\u06a9\u0627\u0631\u0645\u0646\u062a\u0648","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/karmento.ir\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Person","@id":"https:\/\/karmento.ir\/blog\/#\/schema\/person\/0bf55b936876b93c11e0d7bb26e210ec","name":"Niloofar Zamani","image":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/secure.gravatar.com\/avatar\/3068213b58f0a4dfcf6f92653ba666edb8385665b9168848d650cd30cac1f03b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3068213b58f0a4dfcf6f92653ba666edb8385665b9168848d650cd30cac1f03b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3068213b58f0a4dfcf6f92653ba666edb8385665b9168848d650cd30cac1f03b?s=96&d=mm&r=g","caption":"Niloofar Zamani"},"url":"https:\/\/karmento.ir\/blog\/author\/niloofarzamani\/"}]}},"_links":{"self":[{"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/posts\/23033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/comments?post=23033"}],"version-history":[{"count":0,"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/posts\/23033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/media\/23034"}],"wp:attachment":[{"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/media?parent=23033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/categories?post=23033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/karmento.ir\/blog\/wp-json\/wp\/v2\/tags?post=23033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}